{"id":4243,"count":1,"description":"","link":"https:\/\/ichernihivets.com\/uk\/tag\/%d1%8f%d0%ba%d0%b8%d0%b9-%d0%ba%d0%be%d1%80%d0%b8%d1%81%d1%82%d1%83%d1%94%d1%82%d1%8c%d1%81%d1%8f-%d0%bf%d0%be%d0%bf%d1%83%d0%bb%d1%8f%d1%80%d0%bd%d1%96%d1%81%d1%82%d1%8e-%d1%81%d0%b5%d1%80%d0%b5","name":"\u044f\u043a\u0438\u0439 \u043a\u043e\u0440\u0438\u0441\u0442\u0443\u0454\u0442\u044c\u0441\u044f \u043f\u043e\u043f\u0443\u043b\u044f\u0440\u043d\u0456\u0441\u0442\u044e \u0441\u0435\u0440\u0435\u0434 \u043c\u0456\u0441\u0442\u044f\u043d \u0442\u0430 \u0433\u043e\u0441\u0442\u0435\u0439 \u043c\u0456\u0441\u0442\u0430 \u0427\u0435\u0440\u043d\u0456\u0433\u0456\u0432","slug":"%d1%8f%d0%ba%d0%b8%d0%b9-%d0%ba%d0%be%d1%80%d0%b8%d1%81%d1%82%d1%83%d1%94%d1%82%d1%8c%d1%81%d1%8f-%d0%bf%d0%be%d0%bf%d1%83%d0%bb%d1%8f%d1%80%d0%bd%d1%96%d1%81%d1%82%d1%8e-%d1%81%d0%b5%d1%80%d0%b5","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ichernihivets.com\/uk\/wp-json\/wp\/v2\/tags\/4243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ichernihivets.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ichernihivets.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ichernihivets.com\/uk\/wp-json\/wp\/v2\/posts?tags=4243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}